{"id":28113,"date":"2020-03-16T10:42:54","date_gmt":"2020-03-16T09:42:54","guid":{"rendered":"https:\/\/www.speakersacademy.com\/speaker\/anouk-ellen-susan-3\/"},"modified":"2026-07-06T17:40:07","modified_gmt":"2026-07-06T15:40:07","slug":"anouk-ellen-susan","status":"publish","type":"sa_speaker","link":"https:\/\/www.speakersacademy.com\/de\/speaker\/anouk-ellen-susan\/","title":{"rendered":"Anouk Ellen Susan"},"content":{"rendered":"<p>Anouk Ellen Susan ist Expertin im Bereich (Selbst-)Marketing, Netzwerken und deutsch-niederl\u00e4ndische Kultur. Sie setzt sich f\u00fcr Frauen und ihre Karriere ein. Sie hat mehr als 25 Jahre Berufserfahrung im Bereich Marketing &amp; Vertrieb, insbesondere mit internationalem Fokus. Anouk hatte seit ihrem 26. Lebensjahr eine F\u00fchrungsposition, unter anderem als Direktorin des NBTC Holland Marketing in Deutschland. Seit 2019 ist sie selbstst\u00e4ndig als professionelle Rednerin, Beraterin, Moderatorin, Coach und Autorin t\u00e4tig.<\/p>\n<p>Anouk hat in 4 L\u00e4ndern studiert und einen Master of Arts in European Marketing erworben. Dar\u00fcber hinaus ist sie strategische Marketerin (NIMA C in 2010), Professionelle Rednerin (GSA Academy &amp; Steinbeiss Hochschule, 2016) und Systematische Coach (INEKO Institut an der Universit\u00e4t von K\u00f6ln, 2021). Sie arbeitet auch viel mit jungen Menschen zusammen, unter anderem als External Examinator f\u00fcr die Breda University (sie betreut Master- &amp; Bachelor-Studenten) und als Gastdozentin f\u00fcr Marketing am New European Business College in M\u00fcnchen. Sie war Vorsitzende der Deutsch-Niederl\u00e4ndischen Gesellschaft in K\u00f6ln und hat seit ihrem Umzug 2022 nach Bayern einen deutsch-niederl\u00e4ndischen Business Club in M\u00fcnchen mit anderen gegr\u00fcndet.<\/p>\n<p>Anouk Ellen Susan ist zweisprachig (NL+DE) aufgewachsen und spricht insgesamt 4 Sprachen. Sie liebt Herausforderungen, die sie wachsen lassen, und entdeckt gerne Neues, hat 7 B\u00fccher geschrieben und zwei Podcasts gegr\u00fcndet. Sie steht f\u00fcr Klarheit, Leidenschaft und Mut. Ihr Motto lautet: \u201eNEIN hast du, JA kannst du bekommen\u201c.<\/p>\n<p>Ihre Zielgruppe besteht aus KMU-Unternehmen sowie \u00f6ffentlichen und staatlichen Institutionen in einem internationalen Kontext: wie Unternehmen mit einem Fokus auf Europa oder mit einem deutsch\/niederl\u00e4ndischen Hintergrund. Anouk Ellen Susans Keynotes, Masterclasses und Trainings richten sich sowohl an F\u00fchrungskr\u00e4fte als auch an Unternehmensmitarbeiter. Um das bestm\u00f6gliche Ergebnis zu erzielen, wird ihr Ansatz immer auf die spezifischen W\u00fcnsche des Kunden abgestimmt. Anouk Ellen Susan arbeitet in deutscher, niederl\u00e4ndischer und englischer Sprache. Sie kann problemlos zwischen den 3 Sprachen wechseln, auch w\u00e4hrend einer Veranstaltung.<\/p>\n<p>Als Rednerin und Moderatorin begeistert sie ihre Gesch\u00e4ftspartner, Kunden und Teilnehmer mit ihrer pers\u00f6nlichen, kompetenten und inspirierenden Art. Mit viel Erfahrung als Expertin f\u00fcr Marketing &amp; Business Strategy wei\u00df sie, die Inhalte praxisnah zu vermitteln. Sie lebt und arbeitet nach dem einfachen Prinzip: \u201eSei so warm und gro\u00dfz\u00fcgig, wie du selbst empfangen werden m\u00f6chtest.\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anouk Ellen Susan ist Expertin im Bereich (Selbst-)Marketing, Netzwerken und deutsch-niederl\u00e4ndische Kultur. Sie setzt sich f\u00fcr Frauen und ihre Karriere ein. Sie hat mehr als 25 Jahre Berufserfahrung im Bereich Marketing &amp; Vertrieb, insbesondere mit internationalem Fokus. Anouk hatte seit ihrem 26. Lebensjahr eine F\u00fchrungsposition, unter anderem als Direktorin des NBTC Holland Marketing in Deutschland. [&hellip;]<\/p>\n","protected":false},"featured_media":22678,"template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[]},"sa_speaker_category":[11,8,115,16,78,17,18,119,108,81,54],"sa_language":[201,199,214],"sa_employability":[274,226,165,273],"class_list":["post-28113","sa_speaker","type-sa_speaker","status-publish","has-post-thumbnail","hentry","sa_speaker_category-fuehrung-management","sa_speaker_category-kommunikation-medien","sa_speaker_category-kundenorientierung","sa_speaker_category-leadership-entwicklung","sa_speaker_category-lebensstil","sa_speaker_category-marketing-vertrieb","sa_speaker_category-motivation-de","sa_speaker_category-networking-de","sa_speaker_category-persoenliche-entwicklung","sa_speaker_category-strategie","sa_speaker_category-teamarbeit"],"acf":{"sa_introduction":"Anouk Ellen Susan ist Expertin im Bereich (Strategisches) Marketing, Selbstmarketing und der deutsch-niederl\u00e4ndischen Kultur.","sa_one_liner":"Marketing | Vertrieb | Gesch\u00e4ft | Netzwerk","sa_name_title":"","sa_region":[],"sa_degree":"","sa_stars":"","sa_maglr_ids":null,"sa_publications":null,"sa_socials":null,"sa_subjects":[{"sa_subjects_title":"LEKKER anders \u2013 die Nachbarn Niederlande und Deutschland","sa_subjects_information":"<p>Anouk Ellen Susan ist Niederl\u00e4nderin, aufgewachsen in Deutschland, zu Hause in beiden L\u00e4ndern \u2013 sprachlich, emotional und mental. In ihrer Brust schlagen zwei Herzen. Deutschland und die Niederlande sind wichtige Handelspartner \u2013 so nah beieinander und doch so verschieden. Die kulturellen Unterschiede sind gro\u00df, oder anders gesagt: LEKKER anders.<\/p>\n<p>Durch Misskommunikation und Unverst\u00e4ndnis werden Chancen vergeben. Wie kommt man zu einer erfolgreichen Zusammenarbeit, in der das volle Potenzial genutzt wird? Wie kann man sein Marketing darauf anpassen? Was sind die Kulturunterschiede und wie wird unterschiedlich genetzwerkt?<\/p>\n<p>Anouk Ellen Susan spricht \u00fcber ihre 45 Jahre Erfahrung. Neben interessanten Zahlen, Daten und Fakten erz\u00e4hlt sie \u00fcber Erfahrungen und kulturelle Unterschiede auf pers\u00f6nlicher und gesch\u00e4ftlicher Ebene. Eine Keynote, die Sie nicht verpassen sollten, wenn Sie in beiden L\u00e4ndern aktiv sind. Eine Pr\u00e4sentation, die nicht nur den Weg f\u00fcr eine bessere Zusammenarbeit zwischen den beiden L\u00e4ndern ebnet, mehr Effizienz in Ihrem (Marketing-)Ansatz, besseres Netzwerken untereinander, sondern auch das Verst\u00e4ndnis f\u00fcreinander auf beiden Seiten wachsen l\u00e4sst.<\/p>\n"},{"sa_subjects_title":"LEKKER anders NETZWERKEN \u2013 F\u00fcr Anf\u00e4nger und f\u00fcr mehr Vielfalt","sa_subjects_information":"<p><b>Krisen, die sich parallel abspielen, Digitalisierung und zunehmende Spezialisierung: Die Wirtschaft ver\u00e4ndert sich immer schneller. Umso wichtiger ist es in diesen Zeiten, verl\u00e4ssliche Partner, Kunden und Lieferanten zu haben; ein gutes Netzwerk kann f\u00fcr Unternehmen den Unterschied machen. Aber aktives Netzwerken ist nicht jedermanns Sache. Wie f\u00e4ngt man an, wie bekommt man ein buntes Netzwerk &#8211; f\u00fcr mehr Vielfalt &#8211; das erz\u00e4hlt Anouk Ellen Susan in ihrer Keynote.<\/b><\/p>\n<p>Was sind die Vorteile von aktivem Netzwerken? Wie kommt man mit Fremden ins Gespr\u00e4ch? Was ist das richtige Setting f\u00fcr Netzwerkgespr\u00e4che? Worauf muss man achten? Gibt es eine Netzwerk-Etikette? Was ist der beste Weg, um sich Namen zu merken? Wie wird Small Talk zu Smart Talk? Sind Sie bereit f\u00fcr neue Perspektiven? M\u00f6chten Sie mehr dar\u00fcber erfahren, wie online und offline, typisch niederl\u00e4ndisches und typisch deutsches Netzwerken am erfolgreichsten ist? Sind Sie offen f\u00fcr Inspiration und daf\u00fcr, wie M\u00e4nner und Frauen, junge und \u00e4ltere Menschen, erfahrene Unternehmer und junge Starter erfolgreich netzwerken? M\u00f6chten Sie wissen, wie diese Kombination neue M\u00f6glichkeiten schafft und was wir voneinander lernen k\u00f6nnen? Auf diese Fragen geht die Autorin von 2 Netzwerkb\u00fcchern, Anouk Ellen Susan, n\u00e4her ein. Daf\u00fcr interviewte sie zudem 65 Netzwerkexperten. Ihr Motto dabei: Man lernt am besten von den Besten. Neue Impulse und Perspektiven auf das Netzwerken. Die perfekte Keynote f\u00fcr alle, die ihr Netzwerk noch aufbauen m\u00fcssen, mehr Vielfalt in ihrem Netzwerk wollen oder ihre eigenen Netzwerkf\u00e4higkeiten auf ein h\u00f6heres Niveau heben m\u00f6chten. Small Talk war gestern.<\/p>\n<p>Netzwerken ist vielseitig, bunt und darf auch LEKKER anders sein.<\/p>\n"},{"sa_subjects_title":"Sichtbarkeit und (Selbst-)Marketing","sa_subjects_information":"<p>In der (Impuls-)Keynote und den Masterclasses geht es darum, dass Sie in Ihrer Kraft gesehen werden, denn (er)kennt niemand Sie, will niemand Sie. Fokussieren Sie sich nicht auf Ihre Schw\u00e4chen, sondern auf Ihre St\u00e4rken und F\u00e4higkeiten!<\/p>\n<p>Es geht vor allem darum, Spuren zu hinterlassen und Relevanz zu erreichen und nicht alles f\u00fcr jeden zu sein, sondern ganz besonders f\u00fcr diejenigen, die Sie erreichen wollen. Wissen, dass die Kraft in der Wiederholung liegt und Sie auffallen, wenn Sie ein bisschen \u2013 lekker anders sind!<\/p>\n<p>Wie k\u00f6nnen Sie noch mehr Menschen erreichen? Noch ergebnisorientierter arbeiten? Eindruck machen und gesehen werden? Menschen erreichen und begeistern?<\/p>\n<p>Dies geht \u00fcber bessere Positionierung, Selbstmarketing, das Setzen und Erreichen von Zielen, das Erkennen und Ausleben von Leidenschaften, den Mut, neue Perspektiven zu sehen. Das gilt f\u00fcr Mitarbeiter in einem Unternehmen, f\u00fcr Institutionen und f\u00fcr Selbstst\u00e4ndige. Anouk Ellen Susan zeigt die passenden Impulse von Sichtbarkeit und Selbstmarketing, aber auch von Gl\u00fcck und Erfolg.<\/p>\n"},{"sa_subjects_title":"UPGRADE dich selbst! \u2013 Dein n\u00e4chstes Level","sa_subjects_information":"<p>Die Impuls-Keynote \u201cUPGRADE yourself! \u2013 Your next level\u201c von Anouk Ellen Susan ist gemacht f\u00fcr Ihre (weiblichen) Mitarbeiter und F\u00fchrungskr\u00e4fte. M\u00f6chten Sie Ihre Mitarbeiter in ihrer Kraft wachsen lassen und auf ein h\u00f6heres Niveau heben? Ihre Mitarbeiter sollen mehr Selbstvertrauen gewinnen, sich selbst und Ihr Unternehmen besser promoten lernen? Sie m\u00f6chten, dass sie sich st\u00e4rker pr\u00e4sentieren und die Botschaft noch beeindruckender r\u00fcberbringen? Und Sie m\u00f6chten damit auch Ihr Unternehmen verbessern? Sie vertrauen auf die Kraft von Mixed Leadership?<\/p>\n<p>Das Ziel ist, alle bereit zu machen f\u00fcr die n\u00e4chsten \u2018challenge, change &amp; choices\u2019?! So st\u00e4rken Sie Ihre Mitarbeiter f\u00fcr die neuen Herausforderungen.<\/p>\n<p>Darauf ist die Impulslesung ausgerichtet. Mit konkreten \u2018Nuggets\u2019, inspirierendem Storytelling und sehr praxisorientiert. Anouk Ellen Susan sch\u00f6pft aus mehr als 20 Jahren Erfahrung als F\u00fchrungskraft. Die Autorin des Buches \u201cUpgrade yourself \u2013 Souver\u00e4n und selbstbewusst als Frau im Job\u201d hat ihr eigenes Erfolgsmodell entwickelt: der Anouk-Index geht \u00fcber Lernen, Leisten, Preisen und Loslassen. Der Index, den sie entwickelt hat, basiert auf drei S\u00e4ulen: Selbstvertrauen, Selbstentfaltung und Selbstmarketing. Genau: \u201cUPGRADE yourself! \u2013 Your next level\u201c.<\/p>\n"},{"sa_subjects_title":"Present to impress - Erfolgreich pr\u00e4sentieren","sa_subjects_information":"<p>Meetings, Pr\u00e4sentationen, Keynotes und Pitches sind Teil unserer t\u00e4glichen Arbeit. Mit dem richtigen Auftreten und einer einpr\u00e4gsamen, beeindruckenden Pr\u00e4sentation kann sich der Mitarbeiter gut positionieren.<br \/>\nDar\u00fcber hinaus k\u00f6nnen sie sich selbst, ihre Idee oder ihr Projekt und ihr Unternehmen aufwerten. Viele Menschen kennen nicht die notwendigen Tricks, um Eindruck zu machen. In ihrer Masterclass \u201cPresent to impress\u201d macht Anouk Ellen Susan Sie mit allen Facetten einer starken Pr\u00e4sentation vertraut, die Sie dann bei Pr\u00e4sentationen, wichtigen Meetings und Keynotes anwenden k\u00f6nnen. Anouk gibt konkretes Wissen aus ihrer langj\u00e4hrigen Erfahrung als Managerin und Certified Professional Speaker weiter. Sie gibt sehr praktische Hilfsmittel und Tipps, die einfach anzuwenden sind. Der Erfolg wird auf den Mitarbeiter und Ihr Unternehmen abstrahlen!<\/p>\n"}],"sa_faq_items":null,"sa_minimum_price":"1000","sa_maximum_price":"3000","sa_banner_image_id":22679,"sa_videos":null,"sa_order_score":10},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anouk Ellen Susan | Marketing en Cultuur - Speakers Academy<\/title>\n<meta name=\"description\" content=\"Als spreker en dagvoorzitter enthousiasmeert Anouk Ellen Susan, zakenpartners, klanten en deelnemers met haar persoonlijke, bekwame en inspirerende aard.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.speakersacademy.com\/de\/speaker\/anouk-ellen-susan\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anouk Ellen Susan | Marketing en Cultuur - Speakers Academy\" \/>\n<meta property=\"og:description\" content=\"Als spreker en dagvoorzitter enthousiasmeert Anouk Ellen Susan, zakenpartners, klanten en deelnemers met haar persoonlijke, bekwame en inspirerende aard.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.speakersacademy.com\/de\/speaker\/anouk-ellen-susan\/\" \/>\n<meta property=\"og:site_name\" content=\"Speakers Academy\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T15:40:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.speakersacademy.com\/de\/wp-content\/uploads\/sites\/4\/2020\/03\/005_Susan-600-x-800.jpg?image-crop-positioner-ts=1783057697\" \/>\n\t<meta property=\"og:image:width\" content=\"601\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/speaker\\\/anouk-ellen-susan\\\/\",\"url\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/speaker\\\/anouk-ellen-susan\\\/\",\"name\":\"Anouk Ellen Susan | Marketing en Cultuur - Speakers Academy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/speaker\\\/anouk-ellen-susan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/speaker\\\/anouk-ellen-susan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/03\\\/005_Susan-600-x-800.jpg?image-crop-positioner-ts=1783057697\",\"datePublished\":\"2020-03-16T09:42:54+00:00\",\"dateModified\":\"2026-07-06T15:40:07+00:00\",\"description\":\"Als spreker en dagvoorzitter enthousiasmeert Anouk Ellen Susan, zakenpartners, klanten en deelnemers met haar persoonlijke, bekwame en inspirerende aard.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/speaker\\\/anouk-ellen-susan\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/speaker\\\/anouk-ellen-susan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/speaker\\\/anouk-ellen-susan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/03\\\/005_Susan-600-x-800.jpg?image-crop-positioner-ts=1783057697\",\"contentUrl\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/03\\\/005_Susan-600-x-800.jpg?image-crop-positioner-ts=1783057697\",\"width\":601,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/speaker\\\/anouk-ellen-susan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Redner\",\"item\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/speaker\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anouk Ellen Susan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/\",\"name\":\"Speakers Academy\",\"description\":\"Bringing Knowledge to the World\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/#organization\",\"name\":\"Speakers Academy\",\"url\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/04\\\/sa_logo.jpg?image-crop-positioner-ts=1783052674\",\"contentUrl\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/04\\\/sa_logo.jpg?image-crop-positioner-ts=1783052674\",\"width\":696,\"height\":696,\"caption\":\"Speakers Academy\"},\"image\":{\"@id\":\"https:\\\/\\\/www.speakersacademy.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/speakers.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCW5ccMnflvNyiE6cChHDYbw\",\"https:\\\/\\\/www.tiktok.com\\\/@speakers_academy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/speakers-academy\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/54t64RYiW9sDkfJQrUBO90\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anouk Ellen Susan | Marketing en Cultuur - Speakers Academy","description":"Als spreker en dagvoorzitter enthousiasmeert Anouk Ellen Susan, zakenpartners, klanten en deelnemers met haar persoonlijke, bekwame en inspirerende aard.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.speakersacademy.com\/de\/speaker\/anouk-ellen-susan\/","og_locale":"de_DE","og_type":"article","og_title":"Anouk Ellen Susan | Marketing en Cultuur - Speakers Academy","og_description":"Als spreker en dagvoorzitter enthousiasmeert Anouk Ellen Susan, zakenpartners, klanten en deelnemers met haar persoonlijke, bekwame en inspirerende aard.","og_url":"https:\/\/www.speakersacademy.com\/de\/speaker\/anouk-ellen-susan\/","og_site_name":"Speakers Academy","article_modified_time":"2026-07-06T15:40:07+00:00","og_image":[{"width":601,"height":800,"url":"https:\/\/www.speakersacademy.com\/de\/wp-content\/uploads\/sites\/4\/2020\/03\/005_Susan-600-x-800.jpg?image-crop-positioner-ts=1783057697","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.speakersacademy.com\/de\/speaker\/anouk-ellen-susan\/","url":"https:\/\/www.speakersacademy.com\/de\/speaker\/anouk-ellen-susan\/","name":"Anouk Ellen Susan | Marketing en Cultuur - Speakers Academy","isPartOf":{"@id":"https:\/\/www.speakersacademy.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.speakersacademy.com\/de\/speaker\/anouk-ellen-susan\/#primaryimage"},"image":{"@id":"https:\/\/www.speakersacademy.com\/de\/speaker\/anouk-ellen-susan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.speakersacademy.com\/de\/wp-content\/uploads\/sites\/4\/2020\/03\/005_Susan-600-x-800.jpg?image-crop-positioner-ts=1783057697","datePublished":"2020-03-16T09:42:54+00:00","dateModified":"2026-07-06T15:40:07+00:00","description":"Als spreker en dagvoorzitter enthousiasmeert Anouk Ellen Susan, zakenpartners, klanten en deelnemers met haar persoonlijke, bekwame en inspirerende aard.","breadcrumb":{"@id":"https:\/\/www.speakersacademy.com\/de\/speaker\/anouk-ellen-susan\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.speakersacademy.com\/de\/speaker\/anouk-ellen-susan\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.speakersacademy.com\/de\/speaker\/anouk-ellen-susan\/#primaryimage","url":"https:\/\/www.speakersacademy.com\/de\/wp-content\/uploads\/sites\/4\/2020\/03\/005_Susan-600-x-800.jpg?image-crop-positioner-ts=1783057697","contentUrl":"https:\/\/www.speakersacademy.com\/de\/wp-content\/uploads\/sites\/4\/2020\/03\/005_Susan-600-x-800.jpg?image-crop-positioner-ts=1783057697","width":601,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.speakersacademy.com\/de\/speaker\/anouk-ellen-susan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.speakersacademy.com\/de\/"},{"@type":"ListItem","position":2,"name":"Redner","item":"https:\/\/www.speakersacademy.com\/de\/speaker\/"},{"@type":"ListItem","position":3,"name":"Anouk Ellen Susan"}]},{"@type":"WebSite","@id":"https:\/\/www.speakersacademy.com\/de\/#website","url":"https:\/\/www.speakersacademy.com\/de\/","name":"Speakers Academy","description":"Bringing Knowledge to the World","publisher":{"@id":"https:\/\/www.speakersacademy.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.speakersacademy.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.speakersacademy.com\/de\/#organization","name":"Speakers Academy","url":"https:\/\/www.speakersacademy.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.speakersacademy.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.speakersacademy.com\/de\/wp-content\/uploads\/sites\/4\/2025\/04\/sa_logo.jpg?image-crop-positioner-ts=1783052674","contentUrl":"https:\/\/www.speakersacademy.com\/de\/wp-content\/uploads\/sites\/4\/2025\/04\/sa_logo.jpg?image-crop-positioner-ts=1783052674","width":696,"height":696,"caption":"Speakers Academy"},"image":{"@id":"https:\/\/www.speakersacademy.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/speakers.academy\/","https:\/\/www.youtube.com\/channel\/UCW5ccMnflvNyiE6cChHDYbw","https:\/\/www.tiktok.com\/@speakers_academy","https:\/\/www.linkedin.com\/company\/speakers-academy","https:\/\/open.spotify.com\/show\/54t64RYiW9sDkfJQrUBO90"]}]}},"_links":{"self":[{"href":"https:\/\/www.speakersacademy.com\/de\/wp-json\/wp\/v2\/sa_speaker\/28113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.speakersacademy.com\/de\/wp-json\/wp\/v2\/sa_speaker"}],"about":[{"href":"https:\/\/www.speakersacademy.com\/de\/wp-json\/wp\/v2\/types\/sa_speaker"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.speakersacademy.com\/de\/wp-json\/wp\/v2\/media\/22678"}],"wp:attachment":[{"href":"https:\/\/www.speakersacademy.com\/de\/wp-json\/wp\/v2\/media?parent=28113"}],"wp:term":[{"taxonomy":"sa_speaker_category","embeddable":true,"href":"https:\/\/www.speakersacademy.com\/de\/wp-json\/wp\/v2\/sa_speaker_category?post=28113"},{"taxonomy":"sa_language","embeddable":true,"href":"https:\/\/www.speakersacademy.com\/de\/wp-json\/wp\/v2\/sa_language?post=28113"},{"taxonomy":"sa_employability","embeddable":true,"href":"https:\/\/www.speakersacademy.com\/de\/wp-json\/wp\/v2\/sa_employability?post=28113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}